{"id":3,"date":"2024-08-04T16:22:05","date_gmt":"2024-08-04T16:22:05","guid":{"rendered":"https:\/\/labs.942estudio.com\/dolly\/?page_id=3"},"modified":"2025-09-19T18:00:08","modified_gmt":"2025-09-19T18:00:08","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/www.juggersport.com\/de\/datenschutzpolitik\/","title":{"rendered":"Datenschutzrichtlinie"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Wer wir sind<\/strong><\/h2>\r\n<!-- \/wp:post-content --> <!-- wp:paragraph -->Unsere Website-Adresse lautet: https:\/\/www.juggersport.com\/\r\n\r\n<!-- \/wp:paragraph --> <!-- wp:paragraph -->Jugger Sport ist eine Website zur Verbreitung von Sport.\r\n\r\n<!-- \/wp:paragraph --> <!-- wp:heading -->\r\n<h2 class=\"wp-block-heading\">Audiovisuelles geistiges Eigentum<\/h2>\r\n<!-- \/wp:heading --> <!-- wp:paragraph -->Wenn Sie nicht auf einem Foto erscheinen m\u00f6chten, kontaktieren Sie uns.\r\n\r\n<!-- \/wp:paragraph --> <!-- wp:paragraph -->Einige der auf der Website sichtbaren Fotos stammen von Miki Caviedes, Isabel Iv\u00e1n und dem <a href=\"https:\/\/www.abenarabijuggerclub.com\/\" target=\"_blank\" rel=\"noopener\">Abenarabi Jugger Club<\/a>.\r\n\r\n<!-- \/wp:paragraph -->&nbsp;","protected":false},"excerpt":{"rendered":"<p>Wer wir sind Unsere Website-Adresse lautet: https:\/\/www.juggersport.com\/ Jugger Sport ist eine Website zur Verbreitung von Sport. Audiovisuelles geistiges Eigentum Wenn Sie nicht [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.juggersport.com\/de\/wp-json\/wp\/v2\/pages\/3","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.juggersport.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.juggersport.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.juggersport.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.juggersport.com\/de\/wp-json\/wp\/v2\/comments?post=3"}],"version-history":[{"count":2,"href":"https:\/\/www.juggersport.com\/de\/wp-json\/wp\/v2\/pages\/3\/revisions"}],"predecessor-version":[{"id":453,"href":"https:\/\/www.juggersport.com\/de\/wp-json\/wp\/v2\/pages\/3\/revisions\/453"}],"wp:attachment":[{"href":"https:\/\/www.juggersport.com\/de\/wp-json\/wp\/v2\/media?parent=3"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}